{"id":7212,"date":"2017-11-27T16:14:00","date_gmt":"2017-11-27T15:14:00","guid":{"rendered":"https:\/\/www.olikrom.com\/?p=6818"},"modified":"2022-12-21T16:24:44","modified_gmt":"2022-12-21T14:24:44","slug":"bpifrance-le-mot-de-semaine-deep-tech","status":"publish","type":"post","link":"https:\/\/www.olikrom.com\/fr\/blog\/actualites\/bpifrance-le-mot-de-semaine-deep-tech\/","title":{"rendered":"Bpifrance, Le mot de la semaine : Deep Tech"},"content":{"rendered":"<h2>Le mouvement de la Deep Tech<\/h2>\n<p class=\"new-order article-content article-document\" style=\"text-align: justify;\">Toutes les semaines, Bpifrance choisit un mot \u00e0 mettre en avant &#8211; parce qu&rsquo;il est dans l&rsquo;air du temps, parce qu&rsquo;il m\u00e9rite une explication, et, plus encore, parce qu&rsquo;il est pertinent pour vos affaires. Aujourd&rsquo;hui, on s\u2019int\u00e9resse \u00e0 la \u00ab Deep Tech \u00bb.<\/p>\n<p style=\"text-align: justify;\">Cette expression d\u00e9signe les startups de la \u00ab\u00a0<a href=\"http:\/\/www.bpifrance.fr\/A-la-une\/Actualites\/Innovation-la-deep-tech-promet-des-changements-profonds-35589\" target=\"_blank\" rel=\"noopener\">Deep Tech<\/a>\u00a0\u00bb qui proposent des produits ou des services sur la base d\u2019<b>innovations de rupture<\/b>. Leur ambition ? S&rsquo;attaquer \u00e0 la r\u00e9solution des grands d\u00e9fis du XXI<sup>e<\/sup>\u00a0si\u00e8cle : une nouvelle technique pour lutter contre le cancer ou le changement climatique, par exemple. Et tous les domaines sont concern\u00e9s.<br \/>L&rsquo;int\u00e9r\u00eat pour les Deep Tech est mondial et la France peut compter sur l&rsquo;excellence de sa recherche pour briller dans ce domaine.<\/p>\n<p>&nbsp;<\/p>\n<h3 align=\"justify\">OliKrom, le symbole du courant Deep Tech en France<\/h3>\n<p style=\"text-align: justify;\">N\u00e9e des travaux de Jean-Fran\u00e7ois L\u00e9tard, ancien directeur de recherches au CNRS, men\u00e9s au sein de l&rsquo;Institut de chimie de la mati\u00e8re condens\u00e9e de Bordeaux,\u00a0<a href=\"http:\/\/www.bpifrance.fr\/A-la-une\/Actualites\/OliKrom-et-ses-pigments-intelligents-symboles-de-la-deep-tech-35195\" target=\"_blank\" rel=\"noopener\">OliKrom<\/a>\u00a0a d\u00e9velopp\u00e9 des pigments capables de changer de couleur en fonction des modifications de leur environnement : changement de temp\u00e9rature, contraintes de pression, modification de la luminosit\u00e9, pr\u00e9sence d&rsquo;un solvant ou d&rsquo;un gaz&#8230;<\/p>\n<p style=\"text-align: justify;\">Les applications ?\u00a0 Rep\u00e9rer une pi\u00e8ce d&rsquo;avion qui a trop chauff\u00e9 ou qui a re\u00e7u un impact ou encore imaginer des murs dont la peinture change de couleur en fonction du moment de la journ\u00e9e&#8230;<\/p>\n<div class=\"body-block\">\n<p>Inventrice de rev\u00eatements \u00ab intelligents \u00bb qui changent de couleur en fonction de la temp\u00e9rature, de la pression ou de la lumi\u00e8re, OliKrom est une start-up atypique. Bas\u00e9e pr\u00e8s de Bordeaux, elle est un excellent symbole du courant deep tech qui d\u00e9colle en France et dans le monde.<\/p>\n<\/div>\n<div class=\"img-block\">\n<div class=\"img\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-32184 alignright\" src=\"https:\/\/www.olikrom.com\/wp-content\/uploads\/2017\/11\/OliKrom-et-ses-pigments-intelligents-symboles-de-la-deep-tech.webp\" alt=\"OliKrom-et-ses-pigments-intelligents-symboles-de-la-deep-tech\" width=\"708\" height=\"408\" srcset=\"https:\/\/www.olikrom.com\/wp-content\/uploads\/2017\/11\/OliKrom-et-ses-pigments-intelligents-symboles-de-la-deep-tech.webp 708w, https:\/\/www.olikrom.com\/wp-content\/uploads\/2017\/11\/OliKrom-et-ses-pigments-intelligents-symboles-de-la-deep-tech-300x173.webp 300w, https:\/\/www.olikrom.com\/wp-content\/uploads\/2017\/11\/OliKrom-et-ses-pigments-intelligents-symboles-de-la-deep-tech-506x292.webp 506w\" sizes=\"auto, (max-width: 708px) 100vw, 708px\" \/><\/div>\n<\/div>\n<div class=\"content-block\">\n<div>\u00a0<\/div>\n<p>Dans une \u00e9tude parue en avril dernier, le Boston Consulting Group et l&rsquo;organisme Hello Tomorrow indiquent que le nombre de start-up appartenant au nouveau courant de la\u00a0<a href=\"https:\/\/www.bpifrance.fr\/A-la-une\/Actualites\/Qu-est-ce-que-la-Deep-Tech-37852\">deep tech<\/a>\u00a0augmente tr\u00e8s rapidement. Par deep tech on entend de v\u00e9ritables innovations de rupture.<\/p>\n<p>Quelque 3 500 start-up issues de la recherche ont ainsi \u00e9t\u00e9 recens\u00e9es dans le monde entier par le fonds anglais Atomico en 2015, et le nombre de cr\u00e9ations a quintupl\u00e9 chaque ann\u00e9e depuis 2011 de part et d&rsquo;autre de l&rsquo;Atlantique.<\/p>\n<p>Bas\u00e9e \u00e0 Pessac, pr\u00e8s de Bordeaux, OliKrom fait partie de ces nouvelles venues. N\u00e9e des travaux de Jean-Fran\u00e7ois L\u00e9tard, ancien directeur de recherches au CNRS, men\u00e9s au sein de l&rsquo;Institut de chimie de la mati\u00e8re condens\u00e9e de Bordeaux, OliKrom a d\u00e9velopp\u00e9 des pigments capables de changer de couleur en fonction des modifications de leur environnement : changement de temp\u00e9rature, contraintes de pression, modification de la luminosit\u00e9, pr\u00e9sence d&rsquo;un solvant ou d&rsquo;un gaz&#8230; Tr\u00e8s r\u00e9sistants, programmables, ils proposent des changements de couleur, r\u00e9versibles ou non, de mani\u00e8re totalement autonome.<\/p>\n<p>Les applications sont multiples : permettre de rep\u00e9rer d&rsquo;un coup d&rsquo;\u0153il une pi\u00e8ce d&rsquo;un avion qui a trop chauff\u00e9 ou re\u00e7u un impact, imaginer des murs dont la peinture change de couleur en fonction du moment de la journ\u00e9e&#8230;<\/p>\n<p>Autant dire qu&rsquo;OliKrom est l\u2019antith\u00e8se de la start-up mono-produit facilement copiable, active sur un seul march\u00e9. Deux ans et demi apr\u00e8s sa cr\u00e9ation, elle a d\u00e9j\u00e0 sign\u00e9 avec 70 grands groupes partenaires de fili\u00e8res diff\u00e9rentes et est rentable depuis ses d\u00e9buts.<\/p>\n<p>&nbsp;<\/p>\n<h2>D\u00e9buter sur des fondations solides<\/h2>\n<div><img decoding=\"async\" src=\"https:\/\/www.bpifrance.fr\/sites\/default\/files\/inline-images\/logo_olikrom3_medium.jpg\" alt=\"\" data-entity-type=\"file\" data-entity-uuid=\"b24a3bee-c601-4a2f-853e-534a333da31d\" \/><\/div>\n<p><a href=\"https:\/\/www.olikrom.com\/fr\/\" target=\"_blank\" rel=\"noopener\">OliKrom<\/a>\u00a0\u00a0con\u00e7oit et produit pour ses clients industriels, tels que Safran ou Airbus, des solutions compl\u00e8tes (peintures, encres, rev\u00eatements\u2026) d\u00e9velopp\u00e9es sur-mesure, en fonction de leurs besoins. La soci\u00e9t\u00e9 vient d\u2019annoncer un partenariat avec Eiffage afin d&rsquo;am\u00e9liorer, gr\u00e2ce \u00e0 l&rsquo;utilisation de pigments photo-luminescents captant la lumi\u00e8re du jour et celles des phares des voitures, la visibilit\u00e9 des marquages au sol, en particulier la nuit et en conditions m\u00e9t\u00e9os d\u00e9grad\u00e9es.<br \/>R\u00e9alisant aujourd\u2019hui 50 % de son chiffre d\u2019affaires, non d\u00e9voil\u00e9, \u00e0 l\u2019international, OliKrom a pris le temps de m\u00fbrir son projet en s\u2019appuyant sur une cellule de transfert de technologie et des partenaires industriels dont les besoins sont tels qu\u2019ils sont pr\u00eats \u00e0 cofinancer des projets de d\u00e9veloppement sur 2 \u00e0 4 ans.<br \/>Ce business mod\u00e8le pr\u00e9cis et de premiers clients solides ont permis une bonne valorisation d\u00e8s le d\u00e9but. OliKrom cherche maintenant \u00e0 cr\u00e9er un site industriel de 2 000 m<sup>2<\/sup> pr\u00e8s de Bordeaux pour commencer \u00e0 produire en masse ses pigments. Un projet \u00e0 5 millions d&rsquo;euros qui sous-tend toute une logique de cr\u00e9ation d\u2019emplois industriels et R&amp;D non d\u00e9localisables, comme souvent avec les start-up de la deep tech.<\/p>\n<\/div>\n<p><strong>Deep Tech, <a href=\"https:\/\/www.latribune.fr\/technos-medias\/startups-du-laboratoire-a-l-entreprise-l-essor-des-deep-tech-679148.html\">Pour en apprendre plus&#8230;<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le mouvement de la Deep Tech Toutes les semaines, Bpifrance choisit un mot \u00e0 mettre en avant &#8211; parce qu&rsquo;il est dans l&rsquo;air du temps, parce qu&rsquo;il m\u00e9rite une [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":23205,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[367],"tags":[],"class_list":["post-7212","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le mot de la semaine par Bpi France : Deep Tech<\/title>\n<meta name=\"description\" content=\"Deep Tech : Toutes les semaines, Bpifrance choisit un mot parce qu&#039;il est dans l&#039;air du temps sur la base d\u2019innovations de rupture\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.olikrom.com\/fr\/blog\/actualites\/bpifrance-le-mot-de-semaine-deep-tech\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le mot de la semaine par Bpi France : Deep Tech\" \/>\n<meta property=\"og:description\" content=\"Deep Tech : Toutes les semaines, Bpifrance choisit un mot parce qu&#039;il est dans l&#039;air du temps sur la base d\u2019innovations de rupture\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.olikrom.com\/fr\/blog\/actualites\/bpifrance-le-mot-de-semaine-deep-tech\/\" \/>\n<meta property=\"og:site_name\" content=\"OliKrom\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-27T15:14:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-21T14:24:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.olikrom.com\/wp-content\/uploads\/2017\/11\/bpifrance_blog.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"532\" \/>\n\t<meta property=\"og:image:height\" content=\"251\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"olikrom\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"olikrom\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.olikrom.com\\\/fr\\\/blog\\\/actualites\\\/bpifrance-le-mot-de-semaine-deep-tech\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.olikrom.com\\\/fr\\\/blog\\\/actualites\\\/bpifrance-le-mot-de-semaine-deep-tech\\\/\"},\"author\":{\"name\":\"olikrom\",\"@id\":\"https:\\\/\\\/www.olikrom.com\\\/fr\\\/#\\\/schema\\\/person\\\/9df28334ff037f296d71c6cf145904ca\"},\"headline\":\"Bpifrance, Le mot de la semaine : Deep Tech\",\"datePublished\":\"2017-11-27T15:14:00+00:00\",\"dateModified\":\"2022-12-21T14:24:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.olikrom.com\\\/fr\\\/blog\\\/actualites\\\/bpifrance-le-mot-de-semaine-deep-tech\\\/\"},\"wordCount\":828,\"publisher\":{\"@id\":\"https:\\\/\\\/www.olikrom.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.olikrom.com\\\/fr\\\/blog\\\/actualites\\\/bpifrance-le-mot-de-semaine-deep-tech\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.olikrom.com\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/bpifrance_blog.jpg\",\"articleSection\":[\"Actualit\u00e9s\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.olikrom.com\\\/fr\\\/blog\\\/actualites\\\/bpifrance-le-mot-de-semaine-deep-tech\\\/\",\"url\":\"https:\\\/\\\/www.olikrom.com\\\/fr\\\/blog\\\/actualites\\\/bpifrance-le-mot-de-semaine-deep-tech\\\/\",\"name\":\"Le mot de la semaine par Bpi France : Deep Tech\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.olikrom.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.olikrom.com\\\/fr\\\/blog\\\/actualites\\\/bpifrance-le-mot-de-semaine-deep-tech\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.olikrom.com\\\/fr\\\/blog\\\/actualites\\\/bpifrance-le-mot-de-semaine-deep-tech\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.olikrom.com\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/bpifrance_blog.jpg\",\"datePublished\":\"2017-11-27T15:14:00+00:00\",\"dateModified\":\"2022-12-21T14:24:44+00:00\",\"description\":\"Deep Tech : Toutes les semaines, Bpifrance choisit un mot parce qu'il est dans l'air du temps sur la base d\u2019innovations de rupture\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.olikrom.com\\\/fr\\\/blog\\\/actualites\\\/bpifrance-le-mot-de-semaine-deep-tech\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.olikrom.com\\\/fr\\\/blog\\\/actualites\\\/bpifrance-le-mot-de-semaine-deep-tech\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.olikrom.com\\\/fr\\\/blog\\\/actualites\\\/bpifrance-le-mot-de-semaine-deep-tech\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.olikrom.com\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/bpifrance_blog.jpg\",\"contentUrl\":\"https:\\\/\\\/www.olikrom.com\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/bpifrance_blog.jpg\",\"width\":532,\"height\":251,\"caption\":\"bpifrance_blog\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.olikrom.com\\\/fr\\\/blog\\\/actualites\\\/bpifrance-le-mot-de-semaine-deep-tech\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.olikrom.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bpifrance, Le mot de la semaine : Deep Tech\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.olikrom.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.olikrom.com\\\/fr\\\/\",\"name\":\"OliKrom\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.olikrom.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.olikrom.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.olikrom.com\\\/fr\\\/#organization\",\"name\":\"Olikrom\",\"url\":\"https:\\\/\\\/www.olikrom.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.olikrom.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.olikrom.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/olikrom-logo-couleurs-2021-ok.png\",\"contentUrl\":\"https:\\\/\\\/www.olikrom.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/olikrom-logo-couleurs-2021-ok.png\",\"width\":285,\"height\":84,\"caption\":\"Olikrom\"},\"image\":{\"@id\":\"https:\\\/\\\/www.olikrom.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.olikrom.com\\\/fr\\\/#\\\/schema\\\/person\\\/9df28334ff037f296d71c6cf145904ca\",\"name\":\"olikrom\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/610dbff3ea490fd0b981b1b2f5a26a440c8e40f8f474fc7fb84a8ac9573692f1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/610dbff3ea490fd0b981b1b2f5a26a440c8e40f8f474fc7fb84a8ac9573692f1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/610dbff3ea490fd0b981b1b2f5a26a440c8e40f8f474fc7fb84a8ac9573692f1?s=96&d=mm&r=g\",\"caption\":\"olikrom\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le mot de la semaine par Bpi France : Deep Tech","description":"Deep Tech : Toutes les semaines, Bpifrance choisit un mot parce qu'il est dans l'air du temps sur la base d\u2019innovations de rupture","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.olikrom.com\/fr\/blog\/actualites\/bpifrance-le-mot-de-semaine-deep-tech\/","og_locale":"fr_FR","og_type":"article","og_title":"Le mot de la semaine par Bpi France : Deep Tech","og_description":"Deep Tech : Toutes les semaines, Bpifrance choisit un mot parce qu'il est dans l'air du temps sur la base d\u2019innovations de rupture","og_url":"https:\/\/www.olikrom.com\/fr\/blog\/actualites\/bpifrance-le-mot-de-semaine-deep-tech\/","og_site_name":"OliKrom","article_published_time":"2017-11-27T15:14:00+00:00","article_modified_time":"2022-12-21T14:24:44+00:00","og_image":[{"width":532,"height":251,"url":"https:\/\/www.olikrom.com\/wp-content\/uploads\/2017\/11\/bpifrance_blog.jpg","type":"image\/jpeg"}],"author":"olikrom","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"olikrom","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.olikrom.com\/fr\/blog\/actualites\/bpifrance-le-mot-de-semaine-deep-tech\/#article","isPartOf":{"@id":"https:\/\/www.olikrom.com\/fr\/blog\/actualites\/bpifrance-le-mot-de-semaine-deep-tech\/"},"author":{"name":"olikrom","@id":"https:\/\/www.olikrom.com\/fr\/#\/schema\/person\/9df28334ff037f296d71c6cf145904ca"},"headline":"Bpifrance, Le mot de la semaine : Deep Tech","datePublished":"2017-11-27T15:14:00+00:00","dateModified":"2022-12-21T14:24:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.olikrom.com\/fr\/blog\/actualites\/bpifrance-le-mot-de-semaine-deep-tech\/"},"wordCount":828,"publisher":{"@id":"https:\/\/www.olikrom.com\/fr\/#organization"},"image":{"@id":"https:\/\/www.olikrom.com\/fr\/blog\/actualites\/bpifrance-le-mot-de-semaine-deep-tech\/#primaryimage"},"thumbnailUrl":"https:\/\/www.olikrom.com\/wp-content\/uploads\/2017\/11\/bpifrance_blog.jpg","articleSection":["Actualit\u00e9s"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.olikrom.com\/fr\/blog\/actualites\/bpifrance-le-mot-de-semaine-deep-tech\/","url":"https:\/\/www.olikrom.com\/fr\/blog\/actualites\/bpifrance-le-mot-de-semaine-deep-tech\/","name":"Le mot de la semaine par Bpi France : Deep Tech","isPartOf":{"@id":"https:\/\/www.olikrom.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.olikrom.com\/fr\/blog\/actualites\/bpifrance-le-mot-de-semaine-deep-tech\/#primaryimage"},"image":{"@id":"https:\/\/www.olikrom.com\/fr\/blog\/actualites\/bpifrance-le-mot-de-semaine-deep-tech\/#primaryimage"},"thumbnailUrl":"https:\/\/www.olikrom.com\/wp-content\/uploads\/2017\/11\/bpifrance_blog.jpg","datePublished":"2017-11-27T15:14:00+00:00","dateModified":"2022-12-21T14:24:44+00:00","description":"Deep Tech : Toutes les semaines, Bpifrance choisit un mot parce qu'il est dans l'air du temps sur la base d\u2019innovations de rupture","breadcrumb":{"@id":"https:\/\/www.olikrom.com\/fr\/blog\/actualites\/bpifrance-le-mot-de-semaine-deep-tech\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.olikrom.com\/fr\/blog\/actualites\/bpifrance-le-mot-de-semaine-deep-tech\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.olikrom.com\/fr\/blog\/actualites\/bpifrance-le-mot-de-semaine-deep-tech\/#primaryimage","url":"https:\/\/www.olikrom.com\/wp-content\/uploads\/2017\/11\/bpifrance_blog.jpg","contentUrl":"https:\/\/www.olikrom.com\/wp-content\/uploads\/2017\/11\/bpifrance_blog.jpg","width":532,"height":251,"caption":"bpifrance_blog"},{"@type":"BreadcrumbList","@id":"https:\/\/www.olikrom.com\/fr\/blog\/actualites\/bpifrance-le-mot-de-semaine-deep-tech\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.olikrom.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Bpifrance, Le mot de la semaine : Deep Tech"}]},{"@type":"WebSite","@id":"https:\/\/www.olikrom.com\/fr\/#website","url":"https:\/\/www.olikrom.com\/fr\/","name":"OliKrom","description":"","publisher":{"@id":"https:\/\/www.olikrom.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.olikrom.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.olikrom.com\/fr\/#organization","name":"Olikrom","url":"https:\/\/www.olikrom.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.olikrom.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.olikrom.com\/wp-content\/uploads\/2022\/01\/olikrom-logo-couleurs-2021-ok.png","contentUrl":"https:\/\/www.olikrom.com\/wp-content\/uploads\/2022\/01\/olikrom-logo-couleurs-2021-ok.png","width":285,"height":84,"caption":"Olikrom"},"image":{"@id":"https:\/\/www.olikrom.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.olikrom.com\/fr\/#\/schema\/person\/9df28334ff037f296d71c6cf145904ca","name":"olikrom","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/610dbff3ea490fd0b981b1b2f5a26a440c8e40f8f474fc7fb84a8ac9573692f1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/610dbff3ea490fd0b981b1b2f5a26a440c8e40f8f474fc7fb84a8ac9573692f1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/610dbff3ea490fd0b981b1b2f5a26a440c8e40f8f474fc7fb84a8ac9573692f1?s=96&d=mm&r=g","caption":"olikrom"}}]}},"_links":{"self":[{"href":"https:\/\/www.olikrom.com\/fr\/wp-json\/wp\/v2\/posts\/7212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.olikrom.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.olikrom.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.olikrom.com\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.olikrom.com\/fr\/wp-json\/wp\/v2\/comments?post=7212"}],"version-history":[{"count":5,"href":"https:\/\/www.olikrom.com\/fr\/wp-json\/wp\/v2\/posts\/7212\/revisions"}],"predecessor-version":[{"id":32186,"href":"https:\/\/www.olikrom.com\/fr\/wp-json\/wp\/v2\/posts\/7212\/revisions\/32186"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.olikrom.com\/fr\/wp-json\/wp\/v2\/media\/23205"}],"wp:attachment":[{"href":"https:\/\/www.olikrom.com\/fr\/wp-json\/wp\/v2\/media?parent=7212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.olikrom.com\/fr\/wp-json\/wp\/v2\/categories?post=7212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.olikrom.com\/fr\/wp-json\/wp\/v2\/tags?post=7212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}